{"id":2976,"date":"2024-06-26T12:58:56","date_gmt":"2024-06-26T10:58:56","guid":{"rendered":"https:\/\/veact.com\/partner\/"},"modified":"2026-05-13T09:48:40","modified_gmt":"2026-05-13T07:48:40","slug":"partner","status":"publish","type":"page","link":"https:\/\/veact.com\/it\/partner\/","title":{"rendered":"Partner"},"content":{"rendered":"<!--Start Small Stage -->\n\t\t<section class=\"snk-stage snk-stage_small snk-section snk-bg_1\">\n\t\t\t<div class=\"container\">\n\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t<div class=\"snk-stage-copy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h1>Una vasta gamma di applicazioni <\/h1>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_sm\">Un numero sempre crescente di applicazioni innovative e certificate<sup>di<\/sup> applicazioni innovative e certificate di terze parti interagisce con il nostro potente Veact Customer Hub tramite la nostra API Veact Partner Connect.<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-buttons\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-btn-primary\" href=\"https:\/\/veact.com\/it\/chiedi-a-noi\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t\t<span>Chiedi a noi<\/span>\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" fill=\"none\" viewBox=\"0 0 24 24\"><path fill=\"currentColor\" d=\"m13.846 17.654-1.054-1.085 3.82-3.819H4.5v-1.5h12.112l-3.82-3.82 1.054-1.084L19.5 12l-5.654 5.654Z\"\/><\/svg>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\n\n\t<section class=\"snk-section snk-section_noBtm\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"snk-textBlock\">\n\n\t\t\t\t\t\t\t\t<h2>I nostri partner. Ridefinire il post-vendita dell&#8217;auto: Pi\u00f9 facile, pi\u00f9 veloce, e i proprietari di auto lo adorano. <\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\n\t\t<section class=\"snk-section snk-section_teaser snk-partner\">\n\t\t<div class=\"container\">\n\t\t\t\n\t\t\t<div class=\"snk-teaser-container\">\n\t\t\t\t<div class=\"snk-teaser-inner row\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-xl-3\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-card snk-card_linked\" href=\"https:\/\/www.citnow.com\/de\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"snk-card-content\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"snk-card-headline\">CitNow<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_xs\">Una piattaforma basata su app che copre tutte le fasi del customer journey e offre ai vostri clienti un&#8217;esperienza di acquisto e possesso dell&#8217;auto trasparente e semplice.\n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tags\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tag\">Comunicazione video intelligente<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t    <div class=\"snk-card-logo\">\n        <img decoding=\"async\" width=\"222\" height=\"92\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/07\/citnow_partnerlogos_gross_222x92px.png\" class=\"attachment-medium size-medium lazyload\" alt=\"CitNOW_1\" title=\"\" aria-label=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/92;\" \/>    <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-xl-3\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-card snk-card_linked\" href=\"https:\/\/www.pulsmanufaktur.de\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"snk-card-content\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"snk-card-headline\">OnCall<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_xs\">Attrezzati per ogni chiamata! Non appena entriamo in contatto, conosciamo il profilo e lo scopo della chiamata del cliente. Con un solo clic, apriamo il profilo completo del cliente nel Marketing Cloud di VEACT per fornire un&#8217;assistenza immediata, rapida, precisa e personalizzata.  <\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tags\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tag\">Gestione delle chiamate<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t    <div class=\"snk-card-logo\">\n        <img decoding=\"async\" width=\"222\" height=\"92\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/07\/puls-manufaktur_partnerlogos_gross_222x92px.png\" class=\"attachment-medium size-medium lazyload\" alt=\"pulsm OnCall\" title=\"\" aria-label=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/92;\" \/>    <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-xl-3\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-card snk-card_linked\" href=\"https:\/\/www.global-office.de\/erreichbarkeitsservice\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"snk-card-content\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"snk-card-headline\">Ufficio globale<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_xs\">Non perdete pi\u00f9 una chiamata! Con Global Office, la vostra disponibilit\u00e0 rimane professionale e affidabile. La tecnologia moderna e il personale addestrato assicurano che i vostri clienti raggiungano sempre un interlocutore cordiale, per un&#8217;esperienza di prima classe che lascia il segno.  <\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tags\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tag\">Gestione delle chiamate<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t    <div class=\"snk-card-logo\">\n        <img decoding=\"async\" width=\"222\" height=\"92\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/07\/global_officeg_partnerlogos_gross_222x92px.png\" class=\"attachment-medium size-medium lazyload\" alt=\"global_Office\" title=\"\" aria-label=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/92;\" \/>    <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-xl-3\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-card snk-card_linked\" href=\"https:\/\/www.schadenpartner24.de\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"snk-card-content\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"snk-card-headline\">Schadenpartner24<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_xs\">Con Schadenpartner24 avete un partner affidabile al vostro fianco per la gestione dei sinistri. Il loro servizio vi semplifica la denuncia dei danni e vi offre un supporto tempestivo nella liquidazione dei sinistri. <\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tags\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tag\">Sinistri<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t    <div class=\"snk-card-logo\">\n        <img decoding=\"async\" width=\"222\" height=\"92\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/07\/schadenpartner24_partnerlogos_gross_222x92px.png\" class=\"attachment-medium size-medium lazyload\" alt=\"Schadenpartner24\" title=\"\" aria-label=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/92;\" \/>    <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-xl-3\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-card snk-card_linked\" href=\"https:\/\/www.smartloyalty.de\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"snk-card-content\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"snk-card-headline\">Smart Loyalty<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_xs\">Con sistemi di fidelizzazione efficienti e personalizzati e idee di marketing innovative, potete aumentare la fedelt\u00e0 dei vostri clienti esistenti e conquistarne di nuovi.\n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tags\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tag\">Fedelt\u00e0 del cliente<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t    <div class=\"snk-card-logo\">\n        <img decoding=\"async\" width=\"222\" height=\"92\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/07\/smartloyalty-ag_partnerlogos_gross_222x92px.png\" class=\"attachment-medium size-medium lazyload\" alt=\"smartloyalty\" title=\"\" aria-label=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/92;\" \/>    <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/section>\n\n\t\n\n\t<section class=\"snk-section snk-section_noBtm snk-bg_1\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"snk-textBlock\">\n\n\t\t\t\t\t\t\t\t<h2>Per un marketing pi\u00f9 intelligente<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\n\t\t<section class=\"snk-section snk-section_teaser snk-partner snk-bg_1\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"splide splide_custom snk-teaserSlider\">\n\t\t\t<div class=\"splide__track\">\n\t\t\t\t<div class=\"splide__list splide__list-visible\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-card snk-card_linked\" href=\"https:\/\/www.cardess.eu\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"snk-card-content\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"snk-card-headline\">CARDESS<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_xs\">Le capacit\u00e0 di CARDESS spaziano dall&#8217;identificazione delle opportunit\u00e0 di vendita e di assistenza alla creazione di campagne di marketing mirate a partire dai dati dei clienti, fino alla comunicazione digitalizzata con i clienti e alla prenotazione di appuntamenti online.\n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tags\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tag\">Gestione dei lead<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t    <div class=\"snk-card-logo\">\n        <img decoding=\"async\" width=\"222\" height=\"92\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/07\/cardess_partnerlogos_gross_222x92px.png\" class=\"attachment-medium size-medium lazyload\" alt=\"Logo_Cardess\" title=\"\" aria-label=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/92;\" \/>    <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-card snk-card_linked\" href=\"https:\/\/www.autocrm.de\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"snk-card-content\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"snk-card-headline\">Autocrm<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_xs\">Sistema di gestione e controllo dei lead per le concessionarie automobilistiche. Con Autocrm \u00e8 possibile ottimizzare i processi della concessionaria e individuare tempestivamente sviluppi e tendenze. \n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tags\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tag\">Gestione dei lead<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t    <div class=\"snk-card-logo\">\n        <img decoding=\"async\" width=\"222\" height=\"92\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/07\/autocrm_partnerlogos_222x92px.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"autocrm\" title=\"\" aria-label=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/92;\" \/>    <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-card snk-card_linked\" href=\"https:\/\/www.fmade.at\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"snk-card-content\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"snk-card-headline\">fmade<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_xs\">fsales e SMIT offrono funzioni che vanno dalle postazioni di vendita alle campagne di marketing e alle analisi, il tutto in un\u2019interfaccia utente intuitiva e flessibile. Tra i punti di forza si annoverano il configuratore multimarca, la facile creazione e tracciabilit\u00e0 delle campagne di marketing e l\u2019uso della firma elettronica per i documenti in fsales\/SMIT. \n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tags\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tag\">Gestione dei lead<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t    <div class=\"snk-card-logo\">\n        <img decoding=\"async\" width=\"250\" height=\"43\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/07\/fmade_partnerlogos_250x43px.gif\" class=\"attachment-medium size-medium lazyload\" alt=\"fmade\" title=\"\" aria-label=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/43;\" \/>    <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"snk-slider-controls\">\n\t\t\t\t\t<!-- Add the prev \/ next arrows -->\n\t\t\t\t\t<div class=\"splide__arrows\">\n\t\t\t\t\t\t<button class=\"splide__arrow splide__arrow--prev\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" fill=\"none\" viewBox=\"0 0 24 24\"><path fill=\"currentColor\" d=\"m12.946 12-4.6-4.6L9.4 6.346 15.054 12 9.4 17.654 8.346 16.6l4.6-4.6Z\"\/><\/svg>\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<!-- Add progress counter -->\n\t\t\t\t\t\t<div class=\"snk-slider-count js-slider-count\">\n\t\t\t\t\t\t\t<span class=\"js-slider-count-index\"><\/span>\/<span class=\"js-slider-count-total\"><\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<button class=\"splide__arrow splide__arrow--next\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" fill=\"none\" viewBox=\"0 0 24 24\"><path fill=\"currentColor\" d=\"m12.946 12-4.6-4.6L9.4 6.346 15.054 12 9.4 17.654 8.346 16.6l4.6-4.6Z\"\/><\/svg>\t\t\t\t\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/section>\n\n\t\n\n\t<section class=\"snk-section snk-section_noBtm\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"snk-textBlock\">\n\n\t\t\t\t\t\t\t\t<h2>Per standard di servizio pi\u00f9 elevati<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\n\t\t<section class=\"snk-section snk-section_teaser snk-partner\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"splide splide_custom snk-teaserSlider\">\n\t\t\t<div class=\"splide__track\">\n\t\t\t\t<div class=\"splide__list splide__list-visible\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-card snk-card_linked\" href=\"https:\/\/www.autohauskenner.de\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"snk-card-content\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"snk-card-headline\">Die Autohauskenner<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_xs\">Questo strumento completamente automatizzato consente ai concessionari di chiedere ai clienti la loro soddisfazione per il servizio offerto dalla concessionaria e di invitarli a inviare una recensione su AHK\/Google.\n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tags\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tag\">Fedelt\u00e0 del cliente<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t    <div class=\"snk-card-logo\">\n        <img decoding=\"async\" width=\"222\" height=\"92\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/07\/autohauskenner_partnerlogos_222x92px.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"Logo_Autohauskenner\" title=\"\" aria-label=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/92;\" \/>    <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-card snk-card_linked\" href=\"https:\/\/www.efleetcon.com\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"snk-card-content\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"snk-card-headline\">Efleetcon<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_xs\">Soluzioni software e hardware per tutti gli aspetti della gestione dei pneumatici per la registrazione mobile dei dati delle ruote o per l&#8217;archiviazione e il recupero dei pneumatici durante la stagione del cambio ruota. Gestione dei pneumatici\n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tags\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tag\">Gestione dei pneumatici<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t    <div class=\"snk-card-logo\">\n        <img decoding=\"async\" width=\"111\" height=\"46\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/07\/efleetcon_partnerlogos_111x46px.png\" class=\"attachment-medium size-medium lazyload\" alt=\"efleetcon_1\" title=\"\" aria-label=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 111px; --smush-placeholder-aspect-ratio: 111\/46;\" \/>    <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"snk-card snk-card_linked\" href=\"https:\/\/www.vaps.de\/mobility-solutions\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"snk-card-content\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"snk-card-headline\">VAMOSO<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"snk-text_xs\">VAMOSO supporta le concessionarie nella gestione della flotta e in tutte le fasi del processo di noleggio. Consente di mantenere i clienti in movimento quando il loro veicolo \u00e8 in panne, sia a causa di un incidente che di una visita programmata in officina. <\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tags\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-card-tag\">Gestione della flotta<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t    <div class=\"snk-card-logo\">\n        <img decoding=\"async\" width=\"111\" height=\"46\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/07\/vamoso_partnerlogos_111x46px.png\" class=\"attachment-medium size-medium lazyload\" alt=\"Logo_Vamoso\" title=\"\" aria-label=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 111px; --smush-placeholder-aspect-ratio: 111\/46;\" \/>    <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"snk-slider-controls\">\n\t\t\t\t\t<!-- Add the prev \/ next arrows -->\n\t\t\t\t\t<div class=\"splide__arrows\">\n\t\t\t\t\t\t<button class=\"splide__arrow splide__arrow--prev\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" fill=\"none\" viewBox=\"0 0 24 24\"><path fill=\"currentColor\" d=\"m12.946 12-4.6-4.6L9.4 6.346 15.054 12 9.4 17.654 8.346 16.6l4.6-4.6Z\"\/><\/svg>\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<!-- Add progress counter -->\n\t\t\t\t\t\t<div class=\"snk-slider-count js-slider-count\">\n\t\t\t\t\t\t\t<span class=\"js-slider-count-index\"><\/span>\/<span class=\"js-slider-count-total\"><\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<button class=\"splide__arrow splide__arrow--next\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" fill=\"none\" viewBox=\"0 0 24 24\"><path fill=\"currentColor\" d=\"m12.946 12-4.6-4.6L9.4 6.346 15.054 12 9.4 17.654 8.346 16.6l4.6-4.6Z\"\/><\/svg>\t\t\t\t\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/section>\n\n\t\n<section class=\"snk-section_banner\">\n\t<div class=\"container\">\n\t\t<div class=\"snk-banner\">\n\t\t\t<div class=\"row\">\n\t\t\t\t<div class=\"col-12 col-md-6 col-lg-8 col-xl-6 snk-banner-textCol\">\n\t\t\t\t\t<div class=\"snk-banner-text snk-section\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"snk-h1\">Volete migliorare ulteriormente la piattaforma Veact &#8211; e trarne profitto?<\/h2>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Entrate a far parte del Veact Partner Connect e beneficiate del nostro business in crescita, senza dover programmare la vostra interfaccia!<\/p>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-buttons\" style=\"margin-left: 6px;\">\n\t\t\t\t\t\t\t\t<a class=\"snk-btn-primary\" href=\"https:\/\/veact.com\/it\/chiedi-a-noi\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t<span>Chiedi a noi<\/span>\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" fill=\"none\" viewBox=\"0 0 24 24\"><path fill=\"currentColor\" d=\"m13.846 17.654-1.054-1.085 3.82-3.819H4.5v-1.5h12.112l-3.82-3.82 1.054-1.084L19.5 12l-5.654 5.654Z\"\/><\/svg>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-md-6 col-lg-4 col-xl-6\">\n\t\t\t\t\t\t<div class=\"snk-banner-image\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2030\" height=\"1236\" data-src=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/06\/veact-gmbh_blau_conversion_banner_footer_2030x1236px.webp\" class=\"attachment-989 size-989 lazyload\" alt=\"Veact GmbH Logo mit V-f\u00f6rmigem Designelement\" title=\"Veact-gmbh_blau_conversion_banner_footer_2030x1236px.jpg\" aria-label=\"\" data-srcset=\"https:\/\/veact.com\/wp-content\/uploads\/2024\/06\/veact-gmbh_blau_conversion_banner_footer_2030x1236px.webp 2030w, https:\/\/veact.com\/wp-content\/uploads\/2024\/06\/veact-gmbh_blau_conversion_banner_footer_2030x1236px-300x183.webp 300w, https:\/\/veact.com\/wp-content\/uploads\/2024\/06\/veact-gmbh_blau_conversion_banner_footer_2030x1236px-1024x623.webp 1024w, https:\/\/veact.com\/wp-content\/uploads\/2024\/06\/veact-gmbh_blau_conversion_banner_footer_2030x1236px-768x468.webp 768w, https:\/\/veact.com\/wp-content\/uploads\/2024\/06\/veact-gmbh_blau_conversion_banner_footer_2030x1236px-1536x935.webp 1536w\" data-sizes=\"(max-width: 2030px) 100vw, 2030px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2030px; --smush-placeholder-aspect-ratio: 2030\/1236;\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"folder":[35],"class_list":["post-2976","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La nostra rete di partner | Veact<\/title>\n<meta name=\"description\" content=\"Lead management, gestione della flotta, fidelizzazione dei clienti e altro ancora: Ottenete una panoramica dell&#039;innovativo panorama dei partner Veact.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veact.com\/it\/partner\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nostra rete di partner | Veact\" \/>\n<meta property=\"og:description\" content=\"Lead management, gestione della flotta, fidelizzazione dei clienti e altro ancora: Ottenete una panoramica dell&#039;innovativo panorama dei partner Veact.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veact.com\/it\/partner\/\" \/>\n<meta property=\"og:site_name\" content=\"Veact\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/veact\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T07:48:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nostra rete di partner | Veact","description":"Lead management, gestione della flotta, fidelizzazione dei clienti e altro ancora: Ottenete una panoramica dell'innovativo panorama dei partner Veact.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veact.com\/it\/partner\/","og_locale":"it_IT","og_type":"article","og_title":"La nostra rete di partner | Veact","og_description":"Lead management, gestione della flotta, fidelizzazione dei clienti e altro ancora: Ottenete una panoramica dell'innovativo panorama dei partner Veact.","og_url":"https:\/\/veact.com\/it\/partner\/","og_site_name":"Veact","article_publisher":"https:\/\/de-de.facebook.com\/veact\/","article_modified_time":"2026-05-13T07:48:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/veact.com\/it\/partner\/","url":"https:\/\/veact.com\/it\/partner\/","name":"La nostra rete di partner | Veact","isPartOf":{"@id":"https:\/\/veact.com\/it\/#website"},"datePublished":"2024-06-26T10:58:56+00:00","dateModified":"2026-05-13T07:48:40+00:00","description":"Lead management, gestione della flotta, fidelizzazione dei clienti e altro ancora: Ottenete una panoramica dell'innovativo panorama dei partner Veact.","breadcrumb":{"@id":"https:\/\/veact.com\/it\/partner\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veact.com\/it\/partner\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/veact.com\/it\/partner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/veact.com\/it\/"},{"@type":"ListItem","position":2,"name":"Partner"}]},{"@type":"WebSite","@id":"https:\/\/veact.com\/it\/#website","url":"https:\/\/veact.com\/it\/","name":"Veact","description":"","publisher":{"@id":"https:\/\/veact.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veact.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/veact.com\/it\/#organization","name":"Veact","url":"https:\/\/veact.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/veact.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/veact.com\/wp-content\/uploads\/2024\/06\/veact_logo_header_weiss_113x28.svg","contentUrl":"https:\/\/veact.com\/wp-content\/uploads\/2024\/06\/veact_logo_header_weiss_113x28.svg","width":113,"height":28,"caption":"Veact"},"image":{"@id":"https:\/\/veact.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/veact\/","https:\/\/de.linkedin.com\/company\/veact","https:\/\/www.xing.com\/pages\/veactgmbh","https:\/\/www.youtube.com\/channel\/UCeYCzasr_JZsH8z7l3kInPw"]}]}},"_links":{"self":[{"href":"https:\/\/veact.com\/it\/wp-json\/wp\/v2\/pages\/2976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veact.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/veact.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/veact.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/veact.com\/it\/wp-json\/wp\/v2\/comments?post=2976"}],"version-history":[{"count":6,"href":"https:\/\/veact.com\/it\/wp-json\/wp\/v2\/pages\/2976\/revisions"}],"predecessor-version":[{"id":4010,"href":"https:\/\/veact.com\/it\/wp-json\/wp\/v2\/pages\/2976\/revisions\/4010"}],"wp:attachment":[{"href":"https:\/\/veact.com\/it\/wp-json\/wp\/v2\/media?parent=2976"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/veact.com\/it\/wp-json\/wp\/v2\/folder?post=2976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}